{"id":64045,"date":"2024-04-02T18:33:47","date_gmt":"2024-04-02T16:33:47","guid":{"rendered":"https:\/\/magazin.tu-braunschweig.de\/?post_type=kb_events&#038;p=64045"},"modified":"2024-04-02T18:33:47","modified_gmt":"2024-04-02T16:33:47","slug":"wasserbauseminar_2024_05","status":"publish","type":"kb_events","link":"https:\/\/magazin.tu-braunschweig.de\/en\/event\/wasserbauseminar_2024_05\/","title":{"rendered":"Wasserbauseminar"},"content":{"rendered":"<p>Thema wird noch bekannt gegeben<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-64045","kb_events","type-kb_events","status-publish","hentry","kb_cat_events-vortrag","kb_institution_events-abteilung-hydrologie-und-flussgebietsmanagement","kb_institution_events-abteilung-hydromechanik-und-kuesteningenieurwesen","kb_institution_events-abteilung-wasserbau-und-gewaessermorphologie","kb_institution_events-leichtweiss-institut-fuer-wasserbau","kb_location_events-hoersaal-bi-84-1-campus-nord","kb_theme_events-architektur-bauingenieurwesen-umweltwissenschaften","kb_audience_events-interessierte","kb_audience_events-studierende","kb_groups_events-wasserbauseminar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wasserbauseminar - TU Braunschweig | Blogs<\/title>\n<meta name=\"description\" content=\"Thema wird noch bekannt gegeben\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wasserbauseminar - TU Braunschweig | Blogs\" \/>\n<meta property=\"og:description\" content=\"Thema wird noch bekannt gegeben\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/\" \/>\n<meta property=\"og:site_name\" content=\"TU Braunschweig | Blogs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_05\\\/\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_05\\\/\",\"name\":\"Wasserbauseminar - TU Braunschweig | Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\"},\"datePublished\":\"2024-04-02T16:33:47+00:00\",\"description\":\"Thema wird noch bekannt gegeben\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_05\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wasserbauseminar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/\",\"name\":\"TU Braunschweig | Blogs\",\"description\":\"Die Blogs der Technischen Universit\u00e4t Braunschweig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wasserbauseminar - TU Braunschweig | Blogs","description":"Thema wird noch bekannt gegeben","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/","og_locale":"en_US","og_type":"article","og_title":"Wasserbauseminar - TU Braunschweig | Blogs","og_description":"Thema wird noch bekannt gegeben","og_url":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/","og_site_name":"TU Braunschweig | Blogs","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/","url":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/","name":"Wasserbauseminar - TU Braunschweig | Blogs","isPartOf":{"@id":"https:\/\/magazin.tu-braunschweig.de\/#website"},"datePublished":"2024-04-02T16:33:47+00:00","description":"Thema wird noch bekannt gegeben","breadcrumb":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.tu-braunschweig.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/magazin.tu-braunschweig.de\/event\/"},{"@type":"ListItem","position":3,"name":"Wasserbauseminar"}]},{"@type":"WebSite","@id":"https:\/\/magazin.tu-braunschweig.de\/#website","url":"https:\/\/magazin.tu-braunschweig.de\/","name":"TU Braunschweig | Blogs","description":"Die Blogs der Technischen Universit\u00e4t Braunschweig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.tu-braunschweig.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events\/64045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events"}],"about":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/types\/kb_events"}],"wp:attachment":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media?parent=64045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}