{"id":63707,"date":"2024-03-21T13:18:32","date_gmt":"2024-03-21T12:18:32","guid":{"rendered":"https:\/\/magazin.tu-braunschweig.de\/?post_type=kb_events&#038;p=63707"},"modified":"2024-03-21T13:18:32","modified_gmt":"2024-03-21T12:18:32","slug":"health4you-entspannt-durchs-studium","status":"publish","type":"kb_events","link":"https:\/\/magazin.tu-braunschweig.de\/en\/event\/health4you-entspannt-durchs-studium\/","title":{"rendered":"HEALTH4YOU Entspannt durchs Studium"},"content":{"rendered":"<p>Stille und Ruhe sind in der schnelllebigen Welt wertvoller denn je. Auch das Studium bringt viele Herausforderungen mit sich. Umso bedeutsamer ist es, einen Ausgleich zwischen den Phasen von Anspannung und Entspannung zu finden. Diese Balance zu schaffen, mag auf den ersten Blick nicht immer einfach sein.<br \/>\nIn diesem Vortrag wirst du eingeladen, verschiedene Entspannungstechniken zu erkunden und einige davon direkt in der Praxis auszuprobieren. Erg\u00e4nzend erh\u00e4ltst du Einblicke in die Theorie des Stresses und die Bedeutung der Entspannung. Entdecke die Kraft der inneren Ruhe und erfahre, wie du diese inmitten deines Studienalltages integrieren kannst.<\/p>\n","protected":false},"featured_media":63708,"template":"","meta":{"_acf_changed":false},"class_list":["post-63707","kb_events","type-kb_events","status-publish","has-post-thumbnail","hentry","kb_cat_events-seminar","kb_institution_events-studentische-gesundheitsfoerderung-sgf","kb_location_events-online","kb_theme_events-allgemein-und-fachuebergreifend","kb_theme_events-musik-kultur-freizeit-sport","kb_audience_events-studierende","kb_audience_events-tu-intern","kb_groups_events-health4you"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HEALTH4YOU Entspannt durchs Studium - TU Braunschweig | Blogs<\/title>\n<meta name=\"description\" content=\"Stille und Ruhe sind in der schnelllebigen Welt wertvoller denn je. Auch das Studium bringt viele Herausforderungen mit sich. Umso bedeutsamer ist es,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HEALTH4YOU Entspannt durchs Studium - TU Braunschweig | Blogs\" \/>\n<meta property=\"og:description\" content=\"Stille und Ruhe sind in der schnelllebigen Welt wertvoller denn je. Auch das Studium bringt viele Herausforderungen mit sich. Umso bedeutsamer ist es,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/\" \/>\n<meta property=\"og:site_name\" content=\"TU Braunschweig | Blogs\" \/>\n<meta property=\"og:image\" content=\"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/03\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/\",\"name\":\"HEALTH4YOU Entspannt durchs Studium - TU Braunschweig | Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg\",\"datePublished\":\"2024-03-21T12:18:32+00:00\",\"description\":\"Stille und Ruhe sind in der schnelllebigen Welt wertvoller denn je. Auch das Studium bringt viele Herausforderungen mit sich. Umso bedeutsamer ist es,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg\",\"contentUrl\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/health4you-entspannt-durchs-studium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HEALTH4YOU Entspannt durchs Studium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/\",\"name\":\"TU Braunschweig | Blogs\",\"description\":\"Die Blogs der Technischen Universit\u00e4t Braunschweig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HEALTH4YOU Entspannt durchs Studium - TU Braunschweig | Blogs","description":"Stille und Ruhe sind in der schnelllebigen Welt wertvoller denn je. Auch das Studium bringt viele Herausforderungen mit sich. Umso bedeutsamer ist es,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/","og_locale":"en_US","og_type":"article","og_title":"HEALTH4YOU Entspannt durchs Studium - TU Braunschweig | Blogs","og_description":"Stille und Ruhe sind in der schnelllebigen Welt wertvoller denn je. Auch das Studium bringt viele Herausforderungen mit sich. Umso bedeutsamer ist es,","og_url":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/","og_site_name":"TU Braunschweig | Blogs","og_image":[{"width":1080,"height":1080,"url":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/03\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/","url":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/","name":"HEALTH4YOU Entspannt durchs Studium - TU Braunschweig | Blogs","isPartOf":{"@id":"https:\/\/magazin.tu-braunschweig.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/#primaryimage"},"image":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/#primaryimage"},"thumbnailUrl":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/03\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg","datePublished":"2024-03-21T12:18:32+00:00","description":"Stille und Ruhe sind in der schnelllebigen Welt wertvoller denn je. Auch das Studium bringt viele Herausforderungen mit sich. Umso bedeutsamer ist es,","breadcrumb":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/#primaryimage","url":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/03\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg","contentUrl":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/03\/2024-03-21_65fc1c3bd49d2_18.04_EntspanntdurchsStudium.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/health4you-entspannt-durchs-studium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.tu-braunschweig.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/magazin.tu-braunschweig.de\/event\/"},{"@type":"ListItem","position":3,"name":"HEALTH4YOU Entspannt durchs Studium"}]},{"@type":"WebSite","@id":"https:\/\/magazin.tu-braunschweig.de\/#website","url":"https:\/\/magazin.tu-braunschweig.de\/","name":"TU Braunschweig | Blogs","description":"Die Blogs der Technischen Universit\u00e4t Braunschweig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.tu-braunschweig.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events\/63707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events"}],"about":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/types\/kb_events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media\/63708"}],"wp:attachment":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media?parent=63707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}