{"id":63589,"date":"2024-04-02T18:28:16","date_gmt":"2024-04-02T16:28:16","guid":{"rendered":"https:\/\/magazin.tu-braunschweig.de\/?post_type=kb_events&#038;p=63589"},"modified":"2024-04-02T18:37:07","modified_gmt":"2024-04-02T16:37:07","slug":"wasserbauseminar_2024_01","status":"publish","type":"kb_events","link":"https:\/\/magazin.tu-braunschweig.de\/en\/event\/wasserbauseminar_2024_01\/","title":{"rendered":"Die Rolle der Versicherer bei der Katastrophenvorsorge"},"content":{"rendered":"<p>Naturgefahren durch Extremwetterereignissen wie D\u00fcrreperioden und Starkniederschl\u00e4gen k\u00f6nnen nicht verhindert werden. Neben Schutzma\u00dfnahmen ist auch eine Katastrophenvorsorge durch Versicherungen hilfreich. In diesem Vortrag sollen die Grundlagen der Versicherungst\u00e4tigkeit bei der Katastrophenvorsorge erl\u00e4utert werden. Hierzu geh\u00f6ren die Risikoeinsch\u00e4tzung, die Grundlagen der Kostenkalkulation mit Beispielen aus der Praxis: Starkregen in Braunschweig, Hochwasser in der Ahr, das Sturzflutprojekt des GDV, \u00dcberschwemmungsgebiete und andere mehr.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-63589","kb_events","type-kb_events","status-publish","hentry","kb_cat_events-vortrag","kb_institution_events-abteilung-hydrologie-und-flussgebietsmanagement","kb_institution_events-abteilung-hydromechanik-und-kuesteningenieurwesen","kb_institution_events-abteilung-wasserbau-und-gewaessermorphologie","kb_institution_events-leichtweiss-institut-fuer-wasserbau","kb_location_events-hoersaal-bi-84-1-campus-nord","kb_theme_events-architektur-bauingenieurwesen-umweltwissenschaften","kb_audience_events-interessierte","kb_audience_events-studierende","kb_groups_events-wasserbauseminar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Rolle der Versicherer bei der Katastrophenvorsorge - TU Braunschweig | Blogs<\/title>\n<meta name=\"description\" content=\"Naturgefahren durch Extremwetterereignissen wie D\u00fcrreperioden und Starkniederschl\u00e4gen k\u00f6nnen nicht verhindert werden. Neben Schutzma\u00dfnahmen ist auch eine\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Rolle der Versicherer bei der Katastrophenvorsorge - TU Braunschweig | Blogs\" \/>\n<meta property=\"og:description\" content=\"Naturgefahren durch Extremwetterereignissen wie D\u00fcrreperioden und Starkniederschl\u00e4gen k\u00f6nnen nicht verhindert werden. Neben Schutzma\u00dfnahmen ist auch eine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/\" \/>\n<meta property=\"og:site_name\" content=\"TU Braunschweig | Blogs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-02T16:37:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_01\\\/\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_01\\\/\",\"name\":\"Die Rolle der Versicherer bei der Katastrophenvorsorge - TU Braunschweig | Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\"},\"datePublished\":\"2024-04-02T16:28:16+00:00\",\"dateModified\":\"2024-04-02T16:37:07+00:00\",\"description\":\"Naturgefahren durch Extremwetterereignissen wie D\u00fcrreperioden und Starkniederschl\u00e4gen k\u00f6nnen nicht verhindert werden. Neben Schutzma\u00dfnahmen ist auch eine\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_01\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/wasserbauseminar_2024_01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Die Rolle der Versicherer bei der Katastrophenvorsorge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/\",\"name\":\"TU Braunschweig | Blogs\",\"description\":\"Die Blogs der Technischen Universit\u00e4t Braunschweig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Rolle der Versicherer bei der Katastrophenvorsorge - TU Braunschweig | Blogs","description":"Naturgefahren durch Extremwetterereignissen wie D\u00fcrreperioden und Starkniederschl\u00e4gen k\u00f6nnen nicht verhindert werden. Neben Schutzma\u00dfnahmen ist auch eine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/","og_locale":"en_US","og_type":"article","og_title":"Die Rolle der Versicherer bei der Katastrophenvorsorge - TU Braunschweig | Blogs","og_description":"Naturgefahren durch Extremwetterereignissen wie D\u00fcrreperioden und Starkniederschl\u00e4gen k\u00f6nnen nicht verhindert werden. Neben Schutzma\u00dfnahmen ist auch eine","og_url":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/","og_site_name":"TU Braunschweig | Blogs","article_modified_time":"2024-04-02T16:37:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/","url":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/","name":"Die Rolle der Versicherer bei der Katastrophenvorsorge - TU Braunschweig | Blogs","isPartOf":{"@id":"https:\/\/magazin.tu-braunschweig.de\/#website"},"datePublished":"2024-04-02T16:28:16+00:00","dateModified":"2024-04-02T16:37:07+00:00","description":"Naturgefahren durch Extremwetterereignissen wie D\u00fcrreperioden und Starkniederschl\u00e4gen k\u00f6nnen nicht verhindert werden. Neben Schutzma\u00dfnahmen ist auch eine","breadcrumb":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/wasserbauseminar_2024_01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.tu-braunschweig.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/magazin.tu-braunschweig.de\/event\/"},{"@type":"ListItem","position":3,"name":"Die Rolle der Versicherer bei der Katastrophenvorsorge"}]},{"@type":"WebSite","@id":"https:\/\/magazin.tu-braunschweig.de\/#website","url":"https:\/\/magazin.tu-braunschweig.de\/","name":"TU Braunschweig | Blogs","description":"Die Blogs der Technischen Universit\u00e4t Braunschweig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.tu-braunschweig.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events\/63589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events"}],"about":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/types\/kb_events"}],"wp:attachment":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media?parent=63589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}