{"id":63391,"date":"2024-03-06T14:10:50","date_gmt":"2024-03-06T13:10:50","guid":{"rendered":"https:\/\/magazin.tu-braunschweig.de\/?post_type=kb_events&#038;p=63391"},"modified":"2024-04-10T08:51:57","modified_gmt":"2024-04-10T06:51:57","slug":"antrittsvorlesung-dueking-mierwald","status":"publish","type":"kb_events","link":"https:\/\/magazin.tu-braunschweig.de\/en\/event\/antrittsvorlesung-dueking-mierwald\/","title":{"rendered":"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald"},"content":{"rendered":"<p>Antrittsvorlesung von<\/p>\n<ul>\n<li>Prof. Dr. Marcel Mierwald, <a href=\"https:\/\/www.tu-braunschweig.de\/inge\/institut\/team\/geschichte-und-geschichtsdidaktik\" target=\"_blank\" rel=\"noopener\">Institut f\u00fcr Geschichtswissenschaft, Abteilung Geschichte und Geschichtsdidaktik<\/a><br \/>\n<strong>&#8220;Geschichtsdidaktik in einer postdigitalen Welt: Historisches Lehren und Lernen in der medialen Transformation?&#8221;<\/strong><\/li>\n<li>Prof. Dr. Peter D\u00fcking, <a href=\"https:\/\/www.tu-braunschweig.de\/sportwissenschaft\" target=\"_blank\" rel=\"noopener\">Institut f\u00fcr Sportwissenschaft und Bewegungsp\u00e4dagogik<\/a><br \/>\n<strong>&#8220;Individualisierung von Bewegungs- und Trainingsprozessen mithilfe digitaler Technologien&#8221;<\/strong><\/li>\n<\/ul>\n<h3><\/h3>\n<h3><strong>Antrittsvorlesung \u201eGeschichtsdidaktik in einer postdigitalen Welt: Historisches Lehren und Lernen in der medialen Transformation?\u201c von Prof. Dr. Marcel Mierwald<\/strong><\/h3>\n<p>Die Digitalisierung als technologisch-soziales Ph\u00e4nomen durchdringt unseren Alltag und beeinflusst immer st\u00e4rker den Bildungsbereich. So ist auch der heutige Geschichtsunterricht davon gepr\u00e4gt, dass er in einer digitalisierten Welt stattfindet. Basal erkennt man dies nicht zuletzt an zahlreichen digitalen Medien, die dort Verwendung finden. Wie aber ver\u00e4ndert sich historisches Lehren und Lernen genau, wenn neben oder anstatt analogen Medien, wie dem klassischen Schulgeschichtsbuch, vermehrt digitale Medien genutzt werden. Die Antrittsvorlesung geht dieser medialen Transformation exemplarisch anhand von eigener Forschung zu Apps, Lernplattformen und KI-System im Geschichtsunterricht nach. Dabei wird nicht zuletzt gefragt, welche Aufgaben sich f\u00fcr die Geschichtsdidaktik als akademische Disziplin in einer Zeit ergeben, in der die Digitalisierung zur Normalit\u00e4t bzw. die Welt postdigital geworden ist.<\/p>\n<p><strong>Zur Person<br \/>\n<\/strong>Marcel Mierwald ist seit M\u00e4rz 2023 Juniorprofessor f\u00fcr die \u201eDidaktik der Bildungsmedien mit dem Schwerpunkt Geschichte\u201c am Leibniz-Institut f\u00fcr Bildungsmedien | GEI und der Technischen Universit\u00e4t Braunschweig. Er arbeitet in der Abteilung Mediale Transformationen am GEI und lehrt universit\u00e4r in der Geschichtsdidaktik. Er forscht im Bereich des historischen Lehrens und Lernens im digitalen Wandel und der empirischen Geschichtsunterrichtsforschung.<br \/>\nMarcel Mierwald studierte Geschichts-, Politik- und Erziehungswissenschaft an der Freien Universit\u00e4t Berlin und Germanistik auf Lehramt an der Ruhr-Universit\u00e4t Bochum. Er arbeitete als Stipendiat und wissenschaftlicher Mitarbeiter an der Ruhr-Universit\u00e4t Bochum im Arbeitsbereich Didaktik der Geschichte und promovierte 2019 mit einer empirisch-geschichtsdidaktischen Studie zur Wirkung von Lernmaterialien im Sch\u00fclerlabor. Nach dem Referendariat f\u00fcr das Lehramt an Gymnasien und Gesamtschulen war er als Post-Doc in den Projekten \u201eHistorical Thinking Competencies in History\u201c (HiTCH), \u201eMenschen im Bergbau\u201c (MiB) und \u201eEmpowering Police Officers and Teachers in Arguing Against Antisemitism\u201c (EMPATHIA\u00b3) t\u00e4tig. Im WiSe 22\/23 vertrat er die Professur (W2) f\u00fcr \u201eNeuere und Neueste Geschichte und Didaktik der Geschichte\u201c an der Technischen Universit\u00e4t Dresden. Seine Forschungsinteressen umfassen u. a. das Lernen mit (digitalen) Medien, die Erfassung und F\u00f6rderung von historischen Kompetenzen, die Sprachbildung im Fach Geschichte und die Antisemitismusforschung.<\/p>\n<p>&#8212;<\/p>\n<h3><strong>Antrittsvorlesung \u201eIndividualisierung von Bewegungs- und Trainingsprozessen mithilfe digitaler Technologien\u201c <\/strong><strong>von Prof. Dr. Peter D\u00fcking<\/strong><\/h3>\n<p>Jun.-Prof. Dr. Peter D\u00fcking forscht im Bereich der Bewegungs- und Trainingswissenschaften zu akuten Reaktionen und chronischen Adaptionen hervorgerufen durch verschiedene bewegungs- und trainingsinduzierte Reize in verschiedenen Populationen. Ziele der Forschung sind 1) die Analyse und der Vergleich von Bewegungs- und Trainingsinterventionen auf gesundheits- und leistungsrelevante Parameter, 2) die Ableitung von Handlungsempfehlungen zur zielgerichteten und individualisierten Optimierung von Bewegungs- und Trainingsprozessen und 3) die Untersuchung von neuen Technologien zur Verbesserung der Analyse und Optimierung von Bewegungs- und Trainingsinterventionen. H\u00e4ufig untersuchte Populationen sind Breiten- und Leistungssportler*innen, aber auch z.B. klinische Populationen, Arbeitnehmer*innen, Studierende und weitere. Der Forschungsschwerpunkt verwendet verschiedene experimentelle Methoden wie z.B. amperometrische Analysen, Atemgasanalysen, Bioimpedanzanalysen, Dynanometrie, Photoplethysmographie und Elektromyographie. Neben Labordiagnostiken werden auch tragbare Technologien (z.B. Herzfrequenzsensoren) f\u00fcr ambulante Assessments untersucht und ggf. verwendet. Es bestehen interdisziplin\u00e4re Forschungskooperationen mit verschiedenen nationalen und internationalen Partnern.<\/p>\n<p><strong>Zur Person<br \/>\n<\/strong>Peter D\u00fcking studierte International Sports Technology am Royal Melbourne Institute of Technology, Australien, und Human Technology in Sports and Medicine an der Deutschen Sporthochschule K\u00f6ln. Er war anschlie\u00dfend wissenschaftlicher Mitarbeiter an der Mid Sweden University, Schweden, und an der Julius-Maximilians-Universit\u00e4t W\u00fcrzburg, wo 2021 die Promotion zum Thema \u201eMonitoring von Belastungs- und Beanspruchungsmarkern zur individualisierten Steuerung von Trainingsprozessen mithilfe tragbarer Sensorik (Wearable Technology)\u201c erfolgte. Seit August 2023 ist Peter D\u00fcking Juniorprofessor f\u00fcr Sportwissenschaft mit Schwerpunkt Bewegung und Training am <a href=\"https:\/\/www.tu-braunschweig.de\/sportwissenschaft\" target=\"_blank\" rel=\"noopener\">Institut f\u00fcr Sportwissenschaft und Bewegungsp\u00e4dagogik<\/a>.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-63391","kb_events","type-kb_events","status-publish","hentry","kb_cat_events-antrittsvorlesung","kb_cat_events-vortrag","kb_institution_events-institut-fuer-geschichtswissenschaft","kb_institution_events-institut-fuer-sportwissenschaft-und-bewegungspaedagogik","kb_location_events-aula-haus-der-wissenschaft","kb_theme_events-geistes-und-erziehungswissenschaften","kb_groups_events-antrittsvorlesung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald - TU Braunschweig | Blogs<\/title>\n<meta name=\"description\" content=\"Antrittsvorlesung von Prof. Dr. Marcel Mierwald, Institut f\u00fcr Geschichtswissenschaft, Abteilung Geschichte und Geschichtsdidaktik &quot;Geschichtsdidaktik in\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald - TU Braunschweig | Blogs\" \/>\n<meta property=\"og:description\" content=\"Antrittsvorlesung von Prof. Dr. Marcel Mierwald, Institut f\u00fcr Geschichtswissenschaft, Abteilung Geschichte und Geschichtsdidaktik &quot;Geschichtsdidaktik in\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/\" \/>\n<meta property=\"og:site_name\" content=\"TU Braunschweig | Blogs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T06:51:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/antrittsvorlesung-dueking-mierwald\\\/\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/antrittsvorlesung-dueking-mierwald\\\/\",\"name\":\"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald - TU Braunschweig | Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\"},\"datePublished\":\"2024-03-06T13:10:50+00:00\",\"dateModified\":\"2024-04-10T06:51:57+00:00\",\"description\":\"Antrittsvorlesung von Prof. Dr. Marcel Mierwald, Institut f\u00fcr Geschichtswissenschaft, Abteilung Geschichte und Geschichtsdidaktik \\\"Geschichtsdidaktik in\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/antrittsvorlesung-dueking-mierwald\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/antrittsvorlesung-dueking-mierwald\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/antrittsvorlesung-dueking-mierwald\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/\",\"name\":\"TU Braunschweig | Blogs\",\"description\":\"Die Blogs der Technischen Universit\u00e4t Braunschweig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald - TU Braunschweig | Blogs","description":"Antrittsvorlesung von Prof. Dr. Marcel Mierwald, Institut f\u00fcr Geschichtswissenschaft, Abteilung Geschichte und Geschichtsdidaktik \"Geschichtsdidaktik in","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/","og_locale":"en_US","og_type":"article","og_title":"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald - TU Braunschweig | Blogs","og_description":"Antrittsvorlesung von Prof. Dr. Marcel Mierwald, Institut f\u00fcr Geschichtswissenschaft, Abteilung Geschichte und Geschichtsdidaktik \"Geschichtsdidaktik in","og_url":"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/","og_site_name":"TU Braunschweig | Blogs","article_modified_time":"2024-04-10T06:51:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/","url":"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/","name":"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald - TU Braunschweig | Blogs","isPartOf":{"@id":"https:\/\/magazin.tu-braunschweig.de\/#website"},"datePublished":"2024-03-06T13:10:50+00:00","dateModified":"2024-04-10T06:51:57+00:00","description":"Antrittsvorlesung von Prof. Dr. Marcel Mierwald, Institut f\u00fcr Geschichtswissenschaft, Abteilung Geschichte und Geschichtsdidaktik \"Geschichtsdidaktik in","breadcrumb":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/antrittsvorlesung-dueking-mierwald\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.tu-braunschweig.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/magazin.tu-braunschweig.de\/event\/"},{"@type":"ListItem","position":3,"name":"Antrittsvorlesung von Prof. Dr. Peter D\u00fcking, Prof. Dr. Marcel Mierwald"}]},{"@type":"WebSite","@id":"https:\/\/magazin.tu-braunschweig.de\/#website","url":"https:\/\/magazin.tu-braunschweig.de\/","name":"TU Braunschweig | Blogs","description":"Die Blogs der Technischen Universit\u00e4t Braunschweig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.tu-braunschweig.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events\/63391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events"}],"about":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/types\/kb_events"}],"wp:attachment":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media?parent=63391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}