{"id":63227,"date":"2024-02-29T09:21:37","date_gmt":"2024-02-29T08:21:37","guid":{"rendered":"https:\/\/magazin.tu-braunschweig.de\/?post_type=kb_events&#038;p=63227"},"modified":"2024-02-29T09:21:37","modified_gmt":"2024-02-29T08:21:37","slug":"science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime","status":"publish","type":"kb_events","link":"https:\/\/magazin.tu-braunschweig.de\/en\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/","title":{"rendered":"Science Talk: Die Bakterienfresser &#8211; Kampf gegen multiresistente Keime"},"content":{"rendered":"<p>Nach aktuellen Sch\u00e4tzungen der WHO sterben weltweit jedes Jahr bis zu 5 Millionen Menschen an Infektionen durch Erreger, gegen die Antibiotika nicht mehr sch\u00fctzen. Auch in Deutschland verbreiten sich die multiresistenten Erreger. Entstanden sind diese Resistenzen vor allem durch den \u00fcberm\u00e4\u00dfigen Gebrauch von Antibiotika. Durch Antibiotika werden empfindliche Bakterien abget\u00f6tet \u2013 doch die widerstandsf\u00e4higen Bakterien existieren weiter und vermehren sich.<br \/>\nEin Sieg im Kampf gegen multiresistente Keime ist somit dringendst angesagt und mit Hilfe von Bakteriophagen (aus dem Griechischen: \u201eBakterienfresser\u201c, kurz: Phagen) in Zukunft vielleicht zu erreichen. Bakteriophagen &#8211; das sind die Viren, die nur Bakterien erkennen und angreifen k\u00f6nnen und f\u00fcr Menschen sowie f\u00fcr die \u00fcbrige belebte Welt ungef\u00e4hrlich sind. Diese unsichtbaren Helden der Mikrobiologie spielen eine entscheidende Rolle im nat\u00fcrlichen Gleichgewicht der Biosph\u00e4re.<br \/>\nDie Viren k\u00f6nnen nicht nur Infektionen behandeln, sondern auch zum Schutz des Menschen auch vorbeugend eingesetzt werden. Eine besondere F\u00e4higkeit der Bakteriophagen ist es, zwischen \u201eguten\u201c und \u201eschlechten\u201c Bakterien zu unterscheiden und somit aktiv f\u00fcr den Schutz unseres Mikrobioms, also den Schutz der Gesamtheit aller Mikroorganismen (z.B. Bakterien oder Viren), die den Menschen oder andere Lebewesen besiedeln, zu sorgen. Ihr Potenzial erstreckt sich auf die Lebensmittelkette und die Nutztierhaltung, was dazu beitragen k\u00f6nnte, den Einsatz von anderen Antibiotika in der Nahrung zu reduzieren.<br \/>\nDer science talk verspricht faszinierende Einblicke in die Welt der Phagen. Dr. Christine Rohde wird die Grenzen und Potenziale der Phagen und Phagentherapie aufzeigen und einen Ausblick darauf geben, wie diese unsichtbaren Verb\u00fcndeten unseren Weg im Kampf gegen multiresistente Keime leiten k\u00f6nnten.<\/p>\n","protected":false},"featured_media":63228,"template":"","meta":{"_acf_changed":false},"class_list":["post-63227","kb_events","type-kb_events","status-publish","has-post-thumbnail","hentry","kb_cat_events-vortrag","kb_institution_events-phaeno-ggmbh","kb_location_events-phaeno","kb_theme_events-allgemein-und-fachuebergreifend","kb_theme_events-chemie-pharmazie-biowissenschaften-psychologie","kb_audience_events-fachpublikum","kb_audience_events-interessierte","kb_audience_events-lehrerinnen-und-lehrer","kb_audience_events-post-docs","kb_audience_events-promovierende","kb_audience_events-schuelerinnen-und-schueler","kb_audience_events-studieninteressierte","kb_audience_events-studierende","kb_groups_events-science-talk"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Science Talk: Die Bakterienfresser - Kampf gegen multiresistente Keime - TU Braunschweig | Blogs<\/title>\n<meta name=\"description\" content=\"Nach aktuellen Sch\u00e4tzungen der WHO sterben weltweit jedes Jahr bis zu 5 Millionen Menschen an Infektionen durch Erreger, gegen die Antibiotika nicht mehr\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Science Talk: Die Bakterienfresser - Kampf gegen multiresistente Keime - TU Braunschweig | Blogs\" \/>\n<meta property=\"og:description\" content=\"Nach aktuellen Sch\u00e4tzungen der WHO sterben weltweit jedes Jahr bis zu 5 Millionen Menschen an Infektionen durch Erreger, gegen die Antibiotika nicht mehr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/\" \/>\n<meta property=\"og:site_name\" content=\"TU Braunschweig | Blogs\" \/>\n<meta property=\"og:image\" content=\"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/02\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2030\" \/>\n\t<meta property=\"og:image:height\" content=\"1353\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/\",\"name\":\"Science Talk: Die Bakterienfresser - Kampf gegen multiresistente Keime - TU Braunschweig | Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg\",\"datePublished\":\"2024-02-29T08:21:37+00:00\",\"description\":\"Nach aktuellen Sch\u00e4tzungen der WHO sterben weltweit jedes Jahr bis zu 5 Millionen Menschen an Infektionen durch Erreger, gegen die Antibiotika nicht mehr\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/#primaryimage\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg\",\"contentUrl\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg\",\"width\":2030,\"height\":1353},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Science Talk: Die Bakterienfresser &#8211; Kampf gegen multiresistente Keime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/\",\"name\":\"TU Braunschweig | Blogs\",\"description\":\"Die Blogs der Technischen Universit\u00e4t Braunschweig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Science Talk: Die Bakterienfresser - Kampf gegen multiresistente Keime - TU Braunschweig | Blogs","description":"Nach aktuellen Sch\u00e4tzungen der WHO sterben weltweit jedes Jahr bis zu 5 Millionen Menschen an Infektionen durch Erreger, gegen die Antibiotika nicht mehr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/","og_locale":"en_US","og_type":"article","og_title":"Science Talk: Die Bakterienfresser - Kampf gegen multiresistente Keime - TU Braunschweig | Blogs","og_description":"Nach aktuellen Sch\u00e4tzungen der WHO sterben weltweit jedes Jahr bis zu 5 Millionen Menschen an Infektionen durch Erreger, gegen die Antibiotika nicht mehr","og_url":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/","og_site_name":"TU Braunschweig | Blogs","og_image":[{"width":2030,"height":1353,"url":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/02\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/","url":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/","name":"Science Talk: Die Bakterienfresser - Kampf gegen multiresistente Keime - TU Braunschweig | Blogs","isPartOf":{"@id":"https:\/\/magazin.tu-braunschweig.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/#primaryimage"},"image":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/#primaryimage"},"thumbnailUrl":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/02\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg","datePublished":"2024-02-29T08:21:37+00:00","description":"Nach aktuellen Sch\u00e4tzungen der WHO sterben weltweit jedes Jahr bis zu 5 Millionen Menschen an Infektionen durch Erreger, gegen die Antibiotika nicht mehr","breadcrumb":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/#primaryimage","url":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/02\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg","contentUrl":"https:\/\/magazin.tu-braunschweig.de\/wp-content\/uploads\/2024\/02\/2024-02-29_65e03a5a55f83_Rohde_Labor21.jpg","width":2030,"height":1353},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/science-talk-die-bakterienfresser-kampf-gegen-multiresistente-keime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.tu-braunschweig.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/magazin.tu-braunschweig.de\/event\/"},{"@type":"ListItem","position":3,"name":"Science Talk: Die Bakterienfresser &#8211; Kampf gegen multiresistente Keime"}]},{"@type":"WebSite","@id":"https:\/\/magazin.tu-braunschweig.de\/#website","url":"https:\/\/magazin.tu-braunschweig.de\/","name":"TU Braunschweig | Blogs","description":"Die Blogs der Technischen Universit\u00e4t Braunschweig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.tu-braunschweig.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events\/63227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events"}],"about":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/types\/kb_events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media\/63228"}],"wp:attachment":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media?parent=63227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}