{"id":55490,"date":"2023-03-06T14:48:56","date_gmt":"2023-03-06T13:48:56","guid":{"rendered":"https:\/\/magazin.tu-braunschweig.de\/?post_type=kb_events&#038;p=55490"},"modified":"2023-05-23T15:05:30","modified_gmt":"2023-05-23T13:05:30","slug":"braunschweiger-reha-und-sozialmedizinsymposium","status":"publish","type":"kb_events","link":"https:\/\/magazin.tu-braunschweig.de\/en\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/","title":{"rendered":"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun?"},"content":{"rendered":"<p>Psychotherapie ist im Wesentlichen sozialmedizinische und rehabilitationsorientierte Behandlung. Keine andere Therapieform kann gleicherma\u00dfen auf Funktionsebene (Symptombehandlung, z.B. Angstreduktion), F\u00e4higkeitsebene (z.B. Soziales Kompe\u00adtenztraining) und Kontextebene (z.B. Arbeitsplatzanpassung) wirken. Auch geht es nicht prim\u00e4r darum, die Symptome bspw. einer einzelnen depressiven Episode zu beseitigen, sondern Patienten zu vermitteln, wie sie mit ihrer wiederkehrenden Stimmungserkrankung \u00fcber die n\u00e4chsten Lebensjahrzehnte kommen. Insofern ist Psychotherapie als Lebens\u00adspanne-Behandlung zu verstehen, die auch Koordination mit zahlreichen Mitbehandlern, Institutionen und dem Arbeitsplatz erfordert.<br \/>\nWir freuen uns, dass in unserem Symposium Kolleginnen und Kollegen der Psychotherapeutenkammer Niedersachsen und der Deutschen Rentenversicherung Braunschweig-Hannover die Rahmenbedingungen skizzieren werden, die sich mit der neuen Bereichsweiterbildung zur \u201eZusatzbezeichnung Sozialmedizin\u201c f\u00fcr Psychotherapeuten er\u00f6ffnen. Eine rehabilitations- und sozialmedizinische Sicht auf Psychotherapie wird auch von der Deutschen Rentenversicherung gef\u00f6rdert, bspw. mit neuen Behandlungskonzepten f\u00fcr die Verkn\u00fcpfung von station\u00e4ren und ambulanten Rehabilitationsbehandlungen.<br \/>\nDie weiteren Fachvortr\u00e4ge im Symposium berichten Beispiele klinisch bew\u00e4hrter und wissenschaftlich evaluierter arbeitsbezogener Behandlungsans\u00e4tze und Behandlungskoordination.<br \/>\nZukunftsperspektiven werden zur Forschung und zur sozialmedizin- und rehabilitationsorientierten Lehre in der Praxis diskutiert.<\/p>\n<p><a href=\"https:\/\/www.tu-braunschweig.de\/psychologie\/klinische\/braunschweiger-reha-und-sozialmedizinsymposium\" target=\"_blank\" rel=\"noopener\">Das Programm\u00a0<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-55490","kb_events","type-kb_events","status-publish","hentry","kb_cat_events-tagung","kb_institution_events-institut-fuer-psychologie","kb_theme_events-chemie-pharmazie-biowissenschaften-psychologie","kb_audience_events-fachpublikum"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun? - TU Braunschweig | Blogs<\/title>\n<meta name=\"description\" content=\"Psychotherapie ist im Wesentlichen sozialmedizinische und rehabilitationsorientierte Behandlung. Keine andere Therapieform kann gleicherma\u00dfen auf\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun? - TU Braunschweig | Blogs\" \/>\n<meta property=\"og:description\" content=\"Psychotherapie ist im Wesentlichen sozialmedizinische und rehabilitationsorientierte Behandlung. Keine andere Therapieform kann gleicherma\u00dfen auf\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/\" \/>\n<meta property=\"og:site_name\" content=\"TU Braunschweig | Blogs\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T13:05:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/braunschweiger-reha-und-sozialmedizinsymposium\\\/\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/braunschweiger-reha-und-sozialmedizinsymposium\\\/\",\"name\":\"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun? - TU Braunschweig | Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\"},\"datePublished\":\"2023-03-06T13:48:56+00:00\",\"dateModified\":\"2023-05-23T13:05:30+00:00\",\"description\":\"Psychotherapie ist im Wesentlichen sozialmedizinische und rehabilitationsorientierte Behandlung. Keine andere Therapieform kann gleicherma\u00dfen auf\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/braunschweiger-reha-und-sozialmedizinsymposium\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/braunschweiger-reha-und-sozialmedizinsymposium\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/braunschweiger-reha-und-sozialmedizinsymposium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/\",\"name\":\"TU Braunschweig | Blogs\",\"description\":\"Die Blogs der Technischen Universit\u00e4t Braunschweig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun? - TU Braunschweig | Blogs","description":"Psychotherapie ist im Wesentlichen sozialmedizinische und rehabilitationsorientierte Behandlung. Keine andere Therapieform kann gleicherma\u00dfen auf","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/","og_locale":"en_US","og_type":"article","og_title":"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun? - TU Braunschweig | Blogs","og_description":"Psychotherapie ist im Wesentlichen sozialmedizinische und rehabilitationsorientierte Behandlung. Keine andere Therapieform kann gleicherma\u00dfen auf","og_url":"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/","og_site_name":"TU Braunschweig | Blogs","article_modified_time":"2023-05-23T13:05:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/","url":"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/","name":"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun? - TU Braunschweig | Blogs","isPartOf":{"@id":"https:\/\/magazin.tu-braunschweig.de\/#website"},"datePublished":"2023-03-06T13:48:56+00:00","dateModified":"2023-05-23T13:05:30+00:00","description":"Psychotherapie ist im Wesentlichen sozialmedizinische und rehabilitationsorientierte Behandlung. Keine andere Therapieform kann gleicherma\u00dfen auf","breadcrumb":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/braunschweiger-reha-und-sozialmedizinsymposium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.tu-braunschweig.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/magazin.tu-braunschweig.de\/event\/"},{"@type":"ListItem","position":3,"name":"1. Braunschweiger Reha- und Sozialmedizinsymposium: Was hat Psychotherapie mit Rehabilitation und Sozialmedizin zu tun?"}]},{"@type":"WebSite","@id":"https:\/\/magazin.tu-braunschweig.de\/#website","url":"https:\/\/magazin.tu-braunschweig.de\/","name":"TU Braunschweig | Blogs","description":"Die Blogs der Technischen Universit\u00e4t Braunschweig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.tu-braunschweig.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events\/55490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events"}],"about":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/types\/kb_events"}],"wp:attachment":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media?parent=55490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}