{"id":52634,"date":"2022-10-25T16:33:58","date_gmt":"2022-10-25T14:33:58","guid":{"rendered":"https:\/\/magazin.tu-braunschweig.de\/?post_type=kb_events&#038;p=52634"},"modified":"2022-10-25T16:33:58","modified_gmt":"2022-10-25T14:33:58","slug":"geooekologisches-kolloquium-202223_05","status":"publish","type":"kb_events","link":"https:\/\/magazin.tu-braunschweig.de\/en\/event\/geooekologisches-kolloquium-202223_05\/","title":{"rendered":"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation"},"content":{"rendered":"<p>Das Geo\u00f6kologische Kolloquium ist eine hochschul\u00f6ffentliche Vortragsreihe zu aktuellen Themen aus der umweltwissenschaftlichen Forschung sowie angewandten Fragestellungen aus dem Bereich Umweltschutz und Umweltpolitik.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-52634","kb_events","type-kb_events","status-publish","hentry","kb_cat_events-vortrag","kb_institution_events-institut-fuer-geooekologie","kb_institution_events-institut-fuer-geosysteme-und-bioindikation","kb_location_events-online","kb_theme_events-architektur-bauingenieurwesen-umweltwissenschaften","kb_audience_events-post-docs","kb_audience_events-promovierende","kb_audience_events-studierende","kb_groups_events-geooekologisches-kolloquium"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reactive transport modeling: Application to environmental problems and implications for climate change mitigation - TU Braunschweig | Blogs<\/title>\n<meta name=\"description\" content=\"Das Geo\u00f6kologische Kolloquium ist eine hochschul\u00f6ffentliche Vortragsreihe zu aktuellen Themen aus der umweltwissenschaftlichen Forschung sowie angewandten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation - TU Braunschweig | Blogs\" \/>\n<meta property=\"og:description\" content=\"Das Geo\u00f6kologische Kolloquium ist eine hochschul\u00f6ffentliche Vortragsreihe zu aktuellen Themen aus der umweltwissenschaftlichen Forschung sowie angewandten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/\" \/>\n<meta property=\"og:site_name\" content=\"TU Braunschweig | Blogs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/geooekologisches-kolloquium-202223_05\\\/\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/geooekologisches-kolloquium-202223_05\\\/\",\"name\":\"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation - TU Braunschweig | Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\"},\"datePublished\":\"2022-10-25T14:33:58+00:00\",\"description\":\"Das Geo\u00f6kologische Kolloquium ist eine hochschul\u00f6ffentliche Vortragsreihe zu aktuellen Themen aus der umweltwissenschaftlichen Forschung sowie angewandten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/geooekologisches-kolloquium-202223_05\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/geooekologisches-kolloquium-202223_05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/geooekologisches-kolloquium-202223_05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/#website\",\"url\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/\",\"name\":\"TU Braunschweig | Blogs\",\"description\":\"Die Blogs der Technischen Universit\u00e4t Braunschweig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazin.tu-braunschweig.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation - TU Braunschweig | Blogs","description":"Das Geo\u00f6kologische Kolloquium ist eine hochschul\u00f6ffentliche Vortragsreihe zu aktuellen Themen aus der umweltwissenschaftlichen Forschung sowie angewandten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/","og_locale":"en_US","og_type":"article","og_title":"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation - TU Braunschweig | Blogs","og_description":"Das Geo\u00f6kologische Kolloquium ist eine hochschul\u00f6ffentliche Vortragsreihe zu aktuellen Themen aus der umweltwissenschaftlichen Forschung sowie angewandten","og_url":"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/","og_site_name":"TU Braunschweig | Blogs","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/","url":"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/","name":"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation - TU Braunschweig | Blogs","isPartOf":{"@id":"https:\/\/magazin.tu-braunschweig.de\/#website"},"datePublished":"2022-10-25T14:33:58+00:00","description":"Das Geo\u00f6kologische Kolloquium ist eine hochschul\u00f6ffentliche Vortragsreihe zu aktuellen Themen aus der umweltwissenschaftlichen Forschung sowie angewandten","breadcrumb":{"@id":"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/magazin.tu-braunschweig.de\/event\/geooekologisches-kolloquium-202223_05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/magazin.tu-braunschweig.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/magazin.tu-braunschweig.de\/event\/"},{"@type":"ListItem","position":3,"name":"Reactive transport modeling: Application to environmental problems and implications for climate change mitigation"}]},{"@type":"WebSite","@id":"https:\/\/magazin.tu-braunschweig.de\/#website","url":"https:\/\/magazin.tu-braunschweig.de\/","name":"TU Braunschweig | Blogs","description":"Die Blogs der Technischen Universit\u00e4t Braunschweig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazin.tu-braunschweig.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events\/52634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/kb_events"}],"about":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/types\/kb_events"}],"wp:attachment":[{"href":"https:\/\/magazin.tu-braunschweig.de\/en\/wp-json\/wp\/v2\/media?parent=52634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}